{"id":3501,"date":"2024-06-12T15:12:58","date_gmt":"2024-06-12T13:12:58","guid":{"rendered":"https:\/\/cms.elsc.support\/?post_type=case&#038;p=3501"},"modified":"2024-06-27T15:38:52","modified_gmt":"2024-06-27T13:38:52","slug":"due-to-lack-of-current-arms-licenses-to-israelberlin-administrative-court-rejects-urgent-application-against-further-war-weapons-exports","status":"publish","type":"case","link":"https:\/\/elsc.support\/fr\/case\/due-to-lack-of-current-arms-licenses-to-israelberlin-administrative-court-rejects-urgent-application-against-further-war-weapons-exports\/","title":{"rendered":"Berlin Administrative Court Rejects Urgent Application Against Further War Weapons Exports &#8220;Due to Lack of Current Arms Licenses to Israel&#8221;"},"content":{"rendered":"<p><em>Press release of the Berlin Lawyers&#8217; Collective, 11.06.2024<\/em> (<em>Deutsche Version unten<\/em>)<\/p>\n\n\n\n<p>In its decision of 10.06.2024 (Az. VG 2 L 119\/24), the Administrative Court of Berlin rejected the application of three Palestinians in Gaza for the denial of war weapons deliveries to Israel.<\/p>\n\n\n\n<p>The Administrative Court dismissed the application on the grounds that the Federal Government claims that it has not approved any more weapons to Israel since February 2024 and that there is therefore no current reason for a ban. The Administrative Court has not ruled that licenses for the war weapons exports to Israel would be permissible in the current situation. According to the Administrative Court, however, no ban on future war weapons exports is necessary, as the Federal Government has changed its licensing practice since the beginning of 2024 and no new licenses have been issued since then. The court further assumes that the Federal Government will decide on future licenses in accordance with international law and, if necessary, will also make use of the possibility to refuse future license requests. For our clients, however, the decision does not provide sufficient legal certainty. They have no trust that the Federal Government will fulfill its obligations under international law after anti-tank weapons have been supplied by Germany that are already been used against civilians in Gaza.<\/p>\n\n\n\n<p>Ahmed Abed, lawyer and part of the Lawyers&#8217; Collective, explains:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>The German government is keeping secret all information about weapons of war that have already been authorized but not yet delivered. We cannot understand why the Administrative Court does not address the German arms exports mentioned in the <a href=\"https:\/\/content.forensic-architecture.org\/wp-content\/uploads\/2023\/04\/Forensis-Report-German-Arms-Exports-to-Israel-2003-2023.pdf\" target=\"_blank\" rel=\"noopener\">Forensic Architecture report<\/a>, e.g. 500,000 pieces of firearms ammunition. The German government&#8217;s tactic of silence about war weapons and war crimes endangers the lives of our clients. However, the German government has a duty to take all measures to end the genocide in Gaza that has been going on for eight months.<\/p>\n<\/blockquote>\n\n\n\n<p>The Federal Government has kept the information about current licensing procedures secret and also not provided any information on weapons of war that had not been delivered. The Federal Government&#8217;s secrecy deprives the applicants of the the possibility of having future licenses reviewed by the courts The lawyers collective (Anw\u00e4lt:innenkollektiv) will examine the appeal against the decision in detail in order to prevent Germany&#8217;s involvement in Israeli war crimes.<\/p>\n\n\n\n<p>The case is supported by the European Legal Support Center, Lawyers for Palestine for Palestine, Palestine Institute for Public Diplomacy and Forensic Architecture.<br><\/p>\n\n\n\n<p>The case can be supported with a donation here: <a href=\"https:\/\/donorbox.org\/no-weapons-for-genocide-support-our-new-legal-battle-against-germany-s-arms-exports-to-israel\" target=\"_blank\" rel=\"noopener\">https:\/\/donorbox.org\/no-weapons-for-genocide-support-our-new-legal-battle-against-germany-s-arms-exports-to-israel<\/a><\/p>\n\n\n\n<p><br>Press contact: Attorney Ahmed Abed, kontakt@kanzlei-abed.de Tel: +49 (0)151 42868562<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Verwaltungsgericht Berlin weist den Eilantrag gegen weitere Kriegswaffenexporte ab: &#8220;Wegen fehlender aktueller Waffengenehmigungen an Israel&#8221;<\/h2>\n\n\n\n<p>Mit Beschluss vom 10.06.2024 (Az. VG 2 L 119\/24) hat das Verwaltungsgericht Berlin den Antrag von drei Pal\u00e4stinenser:innen in Gaza auf Versagung von Kriegswaffenlieferungen an Israel abgewiesen.<\/p>\n\n\n\n<p>Das Verwaltungsgericht st\u00fctzt sich dabei auf die Aussage der Bundesregierung seit Februar 2024 keine Waffen mehr an Israel genehmigt zu haben. Damit bestehe laut Verwaltungsgericht kein aktueller Anlass f\u00fcr ein Verbot. Das Verwaltungsgericht hat nicht entschieden, dass Genehmigungen von Kriegswaffenexporten nach Israel in der derzeitigen Lage zul\u00e4ssig w\u00e4ren. Laut Verwaltungsgericht ist aber kein Verbot von k\u00fcnftigen Kriegswaffenexporten erforderlich, da die Bundesregierung ihre Genehmigungspraxis seit Anfang 2024 ge\u00e4ndert habe . Das Gericht geht weiter davon aus, dass die Bundesregierung bei k\u00fcnftigen Genehmigungen v\u00f6lkerrechtskonform entscheiden wird und gegebenenfalls auch von der M\u00f6glichkeit Gebrauch machen wird, k\u00fcnftige Genehmigungsanfragen abzulehnen. F\u00fcr unsere Mandant:innen bietet die Entscheidung aber keine ausreichende Rechtssicherheit. Sie verlassen sich nicht darauf, dass die Bundesregierung sich zuk\u00fcnftig an ihre v\u00f6lkerrechtlichen Verpflichtungen halten wird, nachdem bereits aus Deutschland gelieferte Panzerabwehrwaffen im Gaza gegen Zivilist:innen eingesetzt wurden.<\/p>\n\n\n\n<p>Ahmed Abed, Rechtsanwalt und Teil des Anw\u00e4lt:innenkollektivs, erkl\u00e4rt dazu:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201eDie Bundesregierung h\u00e4lt alle Informationen \u00fcber bereits genehmigte, aber noch nicht ausgelieferte Kriegswaffen geheim. Wir k\u00f6nnen nicht nachvollziehen, warum das Verwaltungsgericht nicht auf die im <a href=\"https:\/\/content.forensic-architecture.org\/wp-content\/uploads\/2023\/04\/Forensis-Report-German-Arms-Exports-to-Israel-2003-2023.pdf\" target=\"_blank\" rel=\"noopener\">Bericht von Forensic Architecture<\/a> erw\u00e4hnten deutschen Waffenexporte, z.B. 500.000 St\u00fcck Schusswaffenmunition, eingeht. Die von der Bundesregierung angewendete Taktik des Schweigens \u00fcber Kriegswaffen und Kriegsverbrechen gef\u00e4hrdet das Leben unserer Mandant:innen. Die Bundesregierung hat jedoch die Pflicht, alle Ma\u00dfnahmen zu ergreifen, um den seit acht Monaten andauernden V\u00f6lkermord in Gaza zu beenden.\u201c<\/p>\n<\/blockquote>\n\n\n\n<p>Die Bundesregierung hat im Verfahren vor dem Verwaltungsgericht Berlin die Angaben \u00fcber aktuelle Genehmigungsverfahren geheim gehalten und auch keine Auskunft \u00fcber nicht ausgelieferte Kriegswaffen gegeben. Durch die Geheimhaltung der Bundesregierung wird den Antragsteller:innen die M\u00f6glichkeit genommen, zuk\u00fcnftige Genehmigungen gerichtlich \u00fcberpr\u00fcfen zu lassen. Das Anw\u00e4lt:innenkollektiv wird die Beschwerde gegen den Beschluss eingehend pr\u00fcfen, um die Beteiligung Deutschlands an israelischen Kriegsverbrechen zu verhindern.<\/p>\n\n\n\n<p>Das Verfahren wird unterst\u00fctzt durch European Legal Support Centre, Lawyers for Palestine, Palestine Institute for Public Diplomacy und Forensic Architecture.<\/p>\n\n\n\n<p><br>Hier kann das Verfahren mit einer Spende unterst\u00fctzt werden: <a href=\"https:\/\/donorbox.org\/no-weapons-for-genocide-support-our-new-legal-battle-against-germany-s-arms-exports-to-israel\" target=\"_blank\" rel=\"noopener\">https:\/\/donorbox.org\/no-weapons-for-genocide-support-our-new-legal-battle-against-germany-s-arms-exports-to-israel<\/a><\/p>\n\n\n\n<p><br>Pressekontakt: Rechtsanwalt Ahmed Abed, kontakt@kanzlei-abed.de Tel.: 0151 42868562<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Press release of the Berlin Lawyers&#8217; Collective, 11.06.2024 (Deutsche Version unten) In its decision of 10.06.2024 (Az. VG 2 L 119\/24), the Administrative Court of Berlin rejected the application of three Palestinians in Gaza for the denial of war weapons deliveries to Israel. The Administrative Court dismissed the application on the grounds that the Federal&#8230;<\/p>","protected":false},"featured_media":3503,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"country":[25],"incident_type":[91,153],"case_status":[9],"class_list":["post-3501","case","type-case","status-publish","has-post-thumbnail","hentry","country-de","incident_type-lawsuit","incident_type-weapons","case_status-pending"],"acf":[],"taxonomy_info":{"country":[{"value":25,"label":"Germany"}],"incident_type":[{"value":91,"label":"Lawsuit"},{"value":153,"label":"Weapons"}],"case_status":[{"value":9,"label":"Pending"}]},"featured_image_src_large":["https:\/\/elsc.support\/wp-content\/uploads\/2024\/06\/PM_WaffenexportWeaponExports1-1024x512.png",1024,512,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/elsc.support\/fr\/wp-json\/wp\/v2\/case\/3501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elsc.support\/fr\/wp-json\/wp\/v2\/case"}],"about":[{"href":"https:\/\/elsc.support\/fr\/wp-json\/wp\/v2\/types\/case"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elsc.support\/fr\/wp-json\/wp\/v2\/media\/3503"}],"wp:attachment":[{"href":"https:\/\/elsc.support\/fr\/wp-json\/wp\/v2\/media?parent=3501"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/elsc.support\/fr\/wp-json\/wp\/v2\/country?post=3501"},{"taxonomy":"incident_type","embeddable":true,"href":"https:\/\/elsc.support\/fr\/wp-json\/wp\/v2\/incident_type?post=3501"},{"taxonomy":"case_status","embeddable":true,"href":"https:\/\/elsc.support\/fr\/wp-json\/wp\/v2\/case_status?post=3501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}