{"id":7749,"date":"2025-09-19T15:00:15","date_gmt":"2025-09-19T13:00:15","guid":{"rendered":"https:\/\/elsc.support\/?p=7749"},"modified":"2025-09-20T12:06:13","modified_gmt":"2025-09-20T10:06:13","slug":"the-time-for-accountability-is-now-criminal-complaint-against-german-government-officials-for-aiding-and-abetting-israels-genocide-in-gaza","status":"publish","type":"post","link":"https:\/\/elsc.support\/de\/the-time-for-accountability-is-now-criminal-complaint-against-german-government-officials-for-aiding-and-abetting-israels-genocide-in-gaza\/","title":{"rendered":"The Time for Accountability is Now: Criminal Complaint against German Government Officials for Aiding and Abetting Israel\u2019s Genocide in Gaza"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"531\" src=\"https:\/\/elsc.support\/wp-content\/uploads\/2025\/09\/18SEP-1024x531.png\" alt=\"\" class=\"wp-image-7759\" srcset=\"https:\/\/elsc.support\/wp-content\/uploads\/2025\/09\/18SEP-1024x531.png 1024w, https:\/\/elsc.support\/wp-content\/uploads\/2025\/09\/18SEP-300x156.png 300w, https:\/\/elsc.support\/wp-content\/uploads\/2025\/09\/18SEP-768x398.png 768w, https:\/\/elsc.support\/wp-content\/uploads\/2025\/09\/18SEP-1536x797.png 1536w, https:\/\/elsc.support\/wp-content\/uploads\/2025\/09\/18SEP-2048x1062.png 2048w, https:\/\/elsc.support\/wp-content\/uploads\/2025\/09\/18SEP-18x9.png 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Berlin, September 19, 2025 &#8211; A criminal complaint against German Government officials and arms trade executives was filed today by a collective of lawyers in Berlin with the support of the European Legal Support Center (ELSC), Palestine Institute for Public Diplomacy (PIPD) and Law for Palestine. <a href=\"https:\/\/www.youtube.com\/watch?v=F43NyMcHfgo\" target=\"_blank\" rel=\"noreferrer noopener\">The Complaint was announced at a&nbsp;press conference today.<\/a>&nbsp;<br><br>The charges were filed at the Office of the Federal Prosecutor in Karlsruhe (\u2018Generalbundesanwaltschaft\u2019) against eleven high ranking officials of the former and current German government and CEOs of arms manufacturers, namely former Federal Chancellor &nbsp;Olaf Scholz, former Federal Minister for Foreign Affairs Annalena Baerbock, former Minister for Economic Affairs and Climate Protection Robert Habeck, current Federal Chancellor Friedrich Merz, current Federal Minister for Foreign Affairs Johann Wadephul and Federal Minister for Economic Affairs and Energy Katherina Reiche, Federal Minister of Defense Boris Pistorius, as well as Dr. J\u00f6rg Stratmann, CEO of Rolls-Royce Solutions GmbH, Michael Humbek, CEO of Dynamit Nobel Defence GmbH, and Dr. Alexander Sagel and Susanne Wiegand, current and former CEOs of RENK Group AG.<br><br>The Federal Prosecutor must respect the UN Convention on the Prevention and Punishment of the Crime of Genocide and initiate investigations on potential crimes if sufficient grounds for suspicion are apparent. In <a href=\"https:\/\/elsc.support\/wp-content\/uploads\/2025\/09\/NEW-Strafantrag_Waffenlieferungen_19.9.2025.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">over 100 pages long criminal complaint<\/a> the lawyers provide extensive evidence for the predicate crimes under the <em>Code of Crimes against International Law (CCAIL<\/em>) namely the crime of genocide, crimes against humanity, and war crimes committed by Israel. Furthermore, the complaint provides extensive evidence for aiding and abetting acts of genocide by German officials through the approval of arms deliveries. &nbsp;<br>The weapon deliveries were approved with full awareness that the weapons were enabling crimes against the Palestinian people. They are in no position to claim they &#8220;did not know.&#8221; CEOs of companies that supply weapons are not exempt from their responsibility under international criminal law by virtue of a government export licence. The fact that the exports were approved does not alter their classification as a criminal act of aiding and abetting genocide.<br><br>Germany is one of the biggest supporters to Israel\u2019s annihilation campaign in Gaza. German arms exports to Israel increased tenfold <a href=\"https:\/\/www.lto.de\/recht\/nachrichten\/n\/waffen-lieferungen-ruestung-export-ampel-neuer-rekord\/\" target=\"_blank\" rel=\"noreferrer noopener\">since 2023 and amounted to about half a billion euros (485.103.796 \u20ac) in total<\/a>. In August 2025, German Chancellor Friedrich Merz announced that his government has stopped issuing new export licences for weapons that could be used in Gaza \u201cuntil further notice\u201d. However, existing licences are still being fulfilled, and new licences continue to be approved for arms allegedly not intended for use in Gaza, but effectively still contributing to the killing of civilians in Palestine and the wider region. The Chancellor did not specify how Germany would be able to control where and how those weapons could be used.<br><br>The criminal complaint specifies several weapon systems which were used by the Israeli army in Gaza including combat drones (Heron TP), warships (Sa\u00b4ar 6-class corvette) and various kinds of ammunition (incl. 120 mm tank ammunition) and mechanical parts. Germany has also delivered an abundance of the handheld anti-tank weapon &#8220;Matador&#8221;. It has since become a TikTok trend among Israeli sol<s>i<\/s>diers to film themselves firing those weapons at residential buildings to destroy Palestinian homes for fun.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nadija Samour, ELSC Senior Legal Officer said:<\/strong> <em>&#8220;Officials in the German Government have openly and repeatedly boasted about their unconditional and unlimited support for Israel. Given the undeniable, genocidal consequences of this support,<s> \u2013<\/s> we seek to hold them accountable.&#8221;<\/em>&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lawyer Benjamin D\u00fcsberg, from the Lawyer\u2019s collective said: <\/strong><em>\u201cThe German Federal Public Prosecutor must open an investigation to uphold the rule of law and the integrity of his office. Otherwise, Germany is effectively admitting that its federal prosecution system employs double standards and undermines the purpose of the office. Since filing our first case in 2024, we have compiled overwhelming evidence that cannot be ignored or dismissed.\u201d <\/em>&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Plaintiff Dr. Qassem Massri, Palestinian German pediatrician, originally from Gaza said:<\/strong>&nbsp;<em>\u201cIn the process of this horrendous genocide, that Germany supported with weapons and rhetoric, I lost many family members childhood friends and colleagues&#8230; their voices have been stolen by German weapons. Today we are submitting this complaint, demanding the German government to fulfill its historical responsibility because Never Again must be Never Again for everyone.\u201d<\/em><strong><em> &nbsp;<\/em><\/strong>&nbsp;<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading7749_fcb648-71, .wp-block-kadence-advancedheading.kt-adv-heading7749_fcb648-71[data-kb-block=\"kb-adv-heading7749_fcb648-71\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading7749_fcb648-71 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7749_fcb648-71[data-kb-block=\"kb-adv-heading7749_fcb648-71\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7749_fcb648-71 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7749_fcb648-71[data-kb-block=\"kb-adv-heading7749_fcb648-71\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading7749_fcb648-71 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading7749_fcb648-71\"><br>The ELSC in cooperation with partner organisations has consistently sought legal action to stop the delivery of arms from Germany to Israel and will continue to do so. Right after the International Court of Justince (ICJ) determined in January 2024 that there is a plausible risk of genocide in Gaza and ordered states to prevent it, a <a href=\"https:\/\/elsc.support\/ar\/accountability-now-palestinians-sue-german-government-officials-for-enabling-the-genocide-in-gaza\/\" target=\"_blank\" rel=\"noreferrer noopener\">similiar criminal complaint<\/a> was submitted to the Federal Prosecutor, who refused to open an investigation against the accused German officials who were still in office at the time. Despite mounting evidence submitted by the lawyers, he reasoned his decision by denying violations of international criminal law by Israel and denying German arms being used by Israel to perpetuate these crimes (\u201clack of causality\u201d).\u00a0<br><br>In June 2024 the Administrative Court Berlin <a href=\"https:\/\/elsc.support\/nl\/case\/due-to-lack-of-current-arms-licenses-to-israelberlin-administrative-court-rejects-urgent-application-against-further-war-weapons-exports\/\" target=\"_blank\" rel=\"noreferrer noopener\">rejected an urgent appeal<\/a> to enforce an immediate ban on weapons deliveries to Israel adopting the Federal Government claims that it has not approved any more weapons since February 2024. <a href=\"https:\/\/www.zeit.de\/2025\/35\/ruestungsexport-israel-cdu-spd-gruene\" target=\"_blank\" rel=\"noreferrer noopener\">German newspaper Die Zeit<\/a>, however, has exposed that the government continued to authorise exports while trying to cover it up by sending them in \u201csmaller portions\u201d. Neither the public, nor the parliament has been informed about this. The ELSC has since intervened through urgent appeals to halt deliveries on the <a href=\"https:\/\/elsc.support\/ar\/emergency-motion-against-the-delivery-of-explosives-from-the-german-ship-mv-kathrin-to-israel\/\" target=\"_blank\" rel=\"noreferrer noopener\">German ship MV Kathrin<\/a> and an <a href=\"https:\/\/elsc.support\/ar\/emergency-court-motions-to-stop-elbit-drone-parts-shipment-via-frankfurt-airport\/\" target=\"_blank\" rel=\"noreferrer noopener\">drone part shipments via Frankfurt airport<\/a>, both were also rejected.\u00a0<br><br>Today\u2019s complaint comes days after\u00a0<a href=\"https:\/\/www.ohchr.org\/en\/press-releases\/2025\/09\/israel-has-committed-genocide-gaza-strip-un-commission-finds\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>UN\u2019s Independent International Commission of Inquiry<\/strong><\/a> on Palestine found that Israel has committed <strong>four acts of genocide<\/strong>, defined under the Genocide Convention, against the Palestinians in the Gaza Strip, which joins mounting reports and evidence based declaration by most respected human rights organisations and a resolution passed by the International Association of Genocide Scholars (IAGS) which states that Israel&#8217;s conduct meets the legal definition as laid out in the UN convention on genocide.\u00a0<br><br>The German Federal Prosecutor can no longer shield its ruling elite from accountability and the rule of law. German officials can\u2019t hide behind distorted legal reasoning while denying the mounting evidence for genocide committed with German arms. The time for accountability is now.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading7749_ce5f8a-d4_0, .wp-block-kadence-advancedheading.kt-adv-heading7749_ce5f8a-d4_0[data-kb-block=\"kb-adv-heading7749_ce5f8a-d4_0\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading7749_ce5f8a-d4_0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7749_ce5f8a-d4_0[data-kb-block=\"kb-adv-heading7749_ce5f8a-d4_0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7749_ce5f8a-d4_0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7749_ce5f8a-d4_0[data-kb-block=\"kb-adv-heading7749_ce5f8a-d4_0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading7749_ce5f8a-d4_0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading7749_ce5f8a-d4_0\"><br><a href=\"https:\/\/donorbox.org\/criminal_complaint_german\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/donorbox.org\/criminal_complaint_german\" rel=\"noreferrer noopener\">Donate to help cover the high legal costs. \/ Spendet, um die Kosten f\u00fcr diesen Fall zu decken.<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Es ist Zeit f\u00fcr Gerechtigkeit!<\/strong>&nbsp;<br><strong>Strafantrag gegen Deutsche Regierungsbeamt*innen wegen Beihilfe zum V\u00f6lkermord Israels in Gaza <\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"has--font-size wp-block-paragraph\">Am heutigen Tag wurde ein Strafantrag gegen deutsche Regierungsbeamt*innen und F\u00fchrungskr\u00e4fte der R\u00fcstungsindustrie von dem Berliner Anw\u00e4lt*innenkollektiv eingereicht. Unterst\u00fctzung erhielten sie vom European Legal Support Center (ELSC), von Palestine Institute for Public Diplomacy (PIPD) und von Law for Palestine.<br> &nbsp;<br>Der Strafantrag wurde bei der Generalbundesanwaltschaft in Karlsruhe gegen elf hochrangige Beamt*innen der ehemaligen und aktuellen deutschen Regierung, sowie gegen Gesch\u00e4ftsf\u00fchrer*innen und Vorstandsvorsitzenden von R\u00fcstungsfirmen eingereicht. Beschuldigt werden der ehemalige Bundeskanzler Olaf Scholz, die ehemalige Bundesministerin des Ausw\u00e4rtigen Annalena Baerbock, Bundesminister f\u00fcr Wirtschaft und Klimaschutz Robert Habeck, sowie der aktuelle Bundeskanzler Friedrich Merz, der derzeitige Bundesminister des Ausw\u00e4rtigen Johann Wadephul, die Bundesministerin f\u00fcr Wirtschaft und Energie Katherina Reiche, der Bundesminister der Verteidigung Boris Pistorius, sowie Dr. J\u00f6rg Stratmann, Gesch\u00e4ftsf\u00fchrer der Rolls-Royce Solutions GmbH, Michael Humbek, Gesch\u00e4ftsf\u00fchrer der Dynamit Nobel Defence GmbH, und Dr. Alexander Sagel und Susanne Wiegand, derzeitige und ehemalige Gesch\u00e4ftsf\u00fchrer von der RENK Group AG.<br><br>Die Generalbundesanwaltschaft muss die UN-Konvention \u00fcber die Verh\u00fctung und Bestrafung des V\u00f6lkermordes und das deutsche V\u00f6lkerstrafgesetzbuch einhalten, und bei Vorliegen eines Anfangsverdachts Ermittlungen wegen m\u00f6glicher Straftaten einleiten. In ihrer <a href=\"http:\/\/elsc.support\/wp-content\/uploads\/2025\/09\/NEW-Strafantrag_Waffenlieferungen_19.9.2025.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u00fcber 100 Seiten langen Strafanzeige<\/a> legen die Anw\u00e4lt*innen umfangreiche Nachweise f\u00fcr die vorgeworfenen Beihilfehandlungen vor. Die Beschuldigten Regierungsbeamt*innen haben den Kriegswaffen- und sonstigen R\u00fcstungsexporten zugestimmt und damit die Ausfuhr der Waffen von Deutschland nach Israel erm\u00f6glicht. Diese besetzen die f\u00fcr die Entscheidungen \u00fcber die Genehmigung von Waffen- und sonstigen R\u00fcstungsexporten ma\u00dfgeblichen Ressorts bzw. halten als Kanzler dar\u00fcber hinaus die Richtlinienkompetenz in ihren H\u00e4nden.&nbsp;<br>&nbsp;&nbsp;<br>&nbsp;Die Waffenlieferungen wurden von den Regierungsbeamt*innen in voller Kenntnis der Tatsache genehmigt, dass die Waffen Verbrechen gegen das pal\u00e4stinensische Volk erm\u00f6glichten. Sie k\u00f6nnen nicht behaupten, dass sie \u201enichts davon wussten\u201d. Entscheidungstr\u00e4ger*innen in Unternehmen, welche Waffen ausliefern, werden durch eine staatliche Ausfuhrgenehmigung nicht von ihrer v\u00f6lkerstrafrechtlichen Verantwortlichkeit freigestellt. Dass die Ausfuhren genehmigt wurden, \u00e4ndert demnach nichts an der Einordnung als strafbare Beihilfehandlung.<br><br>&nbsp;Deutschland ist einer der gr\u00f6\u00dften Unterst\u00fctzer der Vernichtungskampagne Israels im Gazastreifen. Die deutschen Waffenexporte nach Israel haben sich seit 2023 verzehnfacht und beliefen sich insgesamt auf etwa eine halbe Milliarde Euro (485.103.796 \u20ac). Im August 2025 gab Bundeskanzler Friedrich Merz bekannt, dass seine Regierung \u201ebis auf Weiteres\u201d keine neuen Ausfuhrgenehmigungen f\u00fcr Waffen mehr erteilt, die im Gazastreifen eingesetzt werden k\u00f6nnten. Bestehende Genehmigungen werden jedoch weiterhin erf\u00fcllt, und neue Genehmigungen werden weiterhin f\u00fcr Waffen erteilt, die angeblich nicht f\u00fcr den Einsatz im Gazastreifen bestimmt sind , aber dennoch zur T\u00f6tung von Zivilisten*innen in Pal\u00e4stina und der gesamten Region beitragen. Der Bundeskanzler hat nicht n\u00e4her erl\u00e4utert, wie Deutschland kontrollieren will, wo und wie diese Waffen eingesetzt werden d\u00fcrfen.<br><br>In dem Strafantrag werden mehrere Waffensysteme genannt, die von der israelischen Armee in Gaza eingesetzt wurden, darunter Kampfdrohnen (Heron TP), Kriegsschiffe (Korvetten der Sa\u00b4ar-6-Klasse) und verschiedene Arten von Munition (u. a. 120-mm-Panzermunition) sowie mechanische Teile. Deutschland hat auch eine gro\u00dfe Menge der tragbaren Panzerabwehrwaffe \u201eMatador\u201c geliefert. Seitdem ist es unter israelischen Soldat*innen zu einem TikTok-Trend geworden, sich selbst dabei zu filmen, wie sie mit diesen Waffen auf Wohngeb\u00e4ude schie\u00dfen, um pal\u00e4stinensische H\u00e4user zum Spa\u00df zu zerst\u00f6ren.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nadija Samour, leitende Rechtsreferentin bei ELSC, sagte:<\/strong> \u201eVertreter der deutschen Regierung haben offen und wiederholt mit ihrer bedingungslosen und uneingeschr\u00e4nkten Unterst\u00fctzung f\u00fcr Israel geprahlt. Angesichts der unbestreitbaren genozidalen Folgen dieser Unterst\u00fctzung m\u00fcssen wir sie zur Rechenschaft ziehen.\u201c&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rechtsanwalt Benjamin D\u00fcsberg vom Anwaltskollektiv sagte: <\/strong>\u201e<em> Der Generalbundesanwalt hat nach dem Legalit\u00e4tsprinzip die Pflicht, Ermittlungen gegen die Beschuldigten einzuleiten. Andernfalls w\u00fcrde er trotz dieser \u00fcberw\u00e4ltigenden Beweislage die Aufnahme von Ermittlungen ablehnen, w\u00fcrde dies einen schweren Versto\u00df gegen Grunds\u00e4tze der Rechtsstaatlichkeit darstellen. Wenn das V\u00f6lkerstrafrecht nicht zu einem blo\u00dfen politischen Instrument verkommen soll, ist es gerade auch auf Regierungspolitiker*innen im eigenen Land anzuwenden. Seit der erstmaligen Ablehnung der Aufnahme von Ermittlungen im Jahr 2024 konnten wir zus\u00e4tzliche \u00fcberw\u00e4ltigende Beweise sammeln, die weder ignoriert noch verworfen werden k\u00f6nnen.<\/em>\u201c&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Der Kl\u00e4ger Dr. Qassem Massri, pal\u00e4stinensisch-deutscher Kinderarzt, urspr\u00fcnglich aus Gaza, sagte:<\/strong>&nbsp;\u201e<em>Ich habe im Zuge dieses grausamen V\u00f6lkermordes der von Deutschland mit Waffen und Rhetorik unterst\u00fctzt wird, viele Familienmitglieder, Kindheitsfreunde und Kollegen verloren. Heute reichen wir diesen Strafantrag ein, damit die Bundesregierung ihrer historischen Verantwortung nachkommt, n\u00e4mlich: Nie wieder f\u00fcr alle.<\/em>\u201c&nbsp;<\/p>\n\n\n\n<p class=\"has--font-size wp-block-paragraph\"><br>Das ELSC hat in Zusammenarbeit mit Partnerorganisationen konsequent rechtliche Schritte eingeleitet, um die Lieferung von Waffen aus Deutschland nach Israel zu stoppen, und wird dies auch weiterhin tun. Unmittelbar nachdem der Internationale Gerichtshof (IGH) im Januar 2024 festgestellt hatte, dass in Gaza ein plausibles Risiko eines V\u00f6lkermords besteht, und die Staaten aufgefordert hatte, dies zu verhindern, wurde eine <a href=\"https:\/\/elsc.support\/ar\/accountability-now-palestinians-sue-german-government-officials-for-enabling-the-genocide-in-gaza\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00e4hnliche Strafanzeige<\/a> bei der Generalbundesanwaltschaft eingereicht, die sich jedoch weigerte, Ermittlungen gegen die beschuldigten deutschen Beamt*innen einzuleiten, die zu diesem Zeitpunkt noch im Amt waren. Trotz der von den Anw\u00e4lt*innen vorgelegten zahlreichen Beweise begr\u00fcndeter seine Entscheidung damit, dass er Verst\u00f6\u00dfe gegen das V\u00f6lkerstrafrecht durch Israel und die Verwendung deutscher Waffen durch Israel zur Fortsetzung dieser Verbrechen (\u201efehlende Kausalit\u00e4t\u201c) bestritt.&nbsp;<br><br>Im Juni 2024 <a href=\"https:\/\/elsc.support\/nl\/case\/due-to-lack-of-current-arms-licenses-to-israelberlin-administrative-court-rejects-urgent-application-against-further-war-weapons-exports\/\" target=\"_blank\" rel=\"noreferrer noopener\">lehnte<\/a> das Verwaltungsgericht Berlin <a href=\"https:\/\/elsc.support\/nl\/case\/due-to-lack-of-current-arms-licenses-to-israelberlin-administrative-court-rejects-urgent-application-against-further-war-weapons-exports\/\" target=\"_blank\" rel=\"noreferrer noopener\">einen Eilantrag<\/a> auf ein sofortiges Verbot von Waffenlieferungen an Israel <a href=\"https:\/\/elsc.support\/nl\/case\/due-to-lack-of-current-arms-licenses-to-israelberlin-administrative-court-rejects-urgent-application-against-further-war-weapons-exports\/\" target=\"_blank\" rel=\"noreferrer noopener\">ab<\/a> und schloss sich damit der Behauptung der Bundesregierung an, dass sie seit Februar 2024 keine Waffen mehr genehmigt habe. Die Zeitung Die Zeit hat jedoch aufgedeckt, dass die Regierung weiterhin Exporte genehmigt hat, w\u00e4hrend sie versuchte, dies zu vertuschen, indem sie sie in \u201ekleineren Portionen\u201c genehmigte . Weder die \u00d6ffentlichkeit, noch das Parlament wurden dar\u00fcber informiert. Das ELSC hat mit dringenden Appellen interveniert, um die Lieferungen auf dem <a href=\"https:\/\/elsc.support\/ar\/emergency-motion-against-the-delivery-of-explosives-from-the-german-ship-mv-kathrin-to-israel\/\" target=\"_blank\" rel=\"noreferrer noopener\">deutschen Schiff MV Kathrin<\/a> und eine <a href=\"https:\/\/elsc.support\/ar\/emergency-court-motions-to-stop-elbit-drone-parts-shipment-via-frankfurt-airport\/\" target=\"_blank\" rel=\"noreferrer noopener\">Drohnenteillieferung \u00fcber den Frankfurter Flughafen<\/a> zu stoppen<a href=\"https:\/\/elsc.support\/ar\/emergency-court-motions-to-stop-elbit-drone-parts-shipment-via-frankfurt-airport\/\" target=\"_blank\" rel=\"noreferrer noopener\">,<\/a> die beide ebenfalls abgelehnt wurden.&nbsp;<br><br>Die heutige Beschwerde kommt wenige Tage, nachdem <a href=\"https:\/\/www.ohchr.org\/en\/press-releases\/2025\/09\/israel-has-committed-genocide-gaza-strip-un-commission-finds\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>die Unabh\u00e4ngige Internationale Untersuchungskommission der Vereinten Nationen<\/strong><\/a> zu Pal\u00e4stina festgestellt hat, dass Israel <strong>vier Akte des V\u00f6lkermords <\/strong>im Sinne der V\u00f6lkermordkonvention gegen die Pal\u00e4stinenser im Gazastreifen begangen hat. Dies reiht sich ein in eine Vielzahl von Berichten der renommiertesten Menschenrechtsorganisationen sowie in eine Resolution der International Association of Genocide Scholars (IAGS), in der festgestellt wird, dass das Verhalten Israels der rechtlichen Definition der V\u00f6lkermordkonvention der Vereinten Nationen entspricht.&nbsp;<br>Die deutsche Generalbundesanwaltschaft kann ihre herrschende Elite nicht l\u00e4nger vor der Verantwortung sch\u00fctzen. Deutsche Beamt*innen k\u00f6nnen sich nicht hinter verzerrten rechtlichen Argumenten verstecken und gleichzeitig die zunehmenden Beweise f\u00fcr V\u00f6lkermord mit deutschen Waffen leugnen. Es ist jetzt an der Zeit, Rechenschaft abzulegen. &nbsp;<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading7749_33a195-30, .wp-block-kadence-advancedheading.kt-adv-heading7749_33a195-30[data-kb-block=\"kb-adv-heading7749_33a195-30\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading7749_33a195-30 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading7749_33a195-30[data-kb-block=\"kb-adv-heading7749_33a195-30\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading7749_33a195-30 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading7749_33a195-30[data-kb-block=\"kb-adv-heading7749_33a195-30\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading7749_33a195-30 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading7749_33a195-30\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berlin, September 19, 2025 &#8211; A criminal complaint against German Government officials and arms trade executives was filed today by a collective of lawyers in Berlin with the support of the European Legal Support Center (ELSC), Palestine Institute for Public Diplomacy (PIPD) and Law for Palestine. The Complaint was announced at a\u00a0press conference today.\u00a0<\/p>","protected":false},"author":11,"featured_media":7755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[55],"tags":[140,143],"test-2":[],"country":[],"blog_categories":[],"class_list":["post-7749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-release","tag-accountability","tag-complicity"],"acf":[],"taxonomy_info":{"category":[{"value":55,"label":"Press Release"}],"post_tag":[{"value":140,"label":"Accountability"},{"value":143,"label":"Complicity"}]},"featured_image_src_large":["https:\/\/elsc.support\/wp-content\/uploads\/2025\/09\/16-1024x538.png",1024,538,true],"author_info":{"display_name":"Bashar","author_link":"https:\/\/elsc.support\/de\/author\/bashar\/"},"comment_info":0,"category_info":[{"term_id":55,"name":"Press Release","slug":"press-release","term_group":0,"term_taxonomy_id":55,"taxonomy":"category","description":"Official updates shared with media or public.","parent":0,"count":82,"filter":"raw","cat_ID":55,"category_count":82,"category_description":"Official updates shared with media or public.","cat_name":"Press Release","category_nicename":"press-release","category_parent":0}],"tag_info":[{"term_id":140,"name":"Accountability","slug":"accountability","term_group":0,"term_taxonomy_id":140,"taxonomy":"post_tag","description":"Legal and institutional accountability","parent":0,"count":28,"filter":"raw"},{"term_id":143,"name":"Complicity","slug":"complicity","term_group":0,"term_taxonomy_id":143,"taxonomy":"post_tag","description":"Complicity of actors in violations","parent":0,"count":23,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/posts\/7749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/comments?post=7749"}],"version-history":[{"count":8,"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/posts\/7749\/revisions"}],"predecessor-version":[{"id":7769,"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/posts\/7749\/revisions\/7769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/media\/7755"}],"wp:attachment":[{"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/media?parent=7749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/categories?post=7749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/tags?post=7749"},{"taxonomy":"test-2","embeddable":true,"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/test-2?post=7749"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/country?post=7749"},{"taxonomy":"blog_categories","embeddable":true,"href":"https:\/\/elsc.support\/de\/wp-json\/wp\/v2\/blog_categories?post=7749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}